{"id":3036,"date":"2026-04-21T08:28:09","date_gmt":"2026-04-21T06:28:09","guid":{"rendered":"https:\/\/tt-meisterschaft.at\/ttbv\/?p=3036"},"modified":"2026-04-21T08:33:53","modified_gmt":"2026-04-21T06:33:53","slug":"saisonabschlussfeier-2025-2026-und-fruehjahrsturnier-2026-ergebnisse","status":"publish","type":"post","link":"https:\/\/tt-meisterschaft.at\/ttbv\/saisonabschlussfeier-2025-2026-und-fruehjahrsturnier-2026-ergebnisse\/","title":{"rendered":"Saisonabschlussfeier 2025\/2026 und Fr\u00fchjahrsturnier 2026 &#8211; Ergebnisse"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/Ergebnisse-Banken-TT-Turnier-04.2026-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Einbettung von Ergebnisse Banken TT-Turnier 04.2026.\"><\/object><a id=\"wp-block-file--media-898f4394-a88a-4e5d-90a1-5f5a790892ab\" href=\"https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/Ergebnisse-Banken-TT-Turnier-04.2026-1.pdf\">Ergebnisse Banken TT-Turnier 04.2026<\/a><a href=\"https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/Ergebnisse-Banken-TT-Turnier-04.2026-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-898f4394-a88a-4e5d-90a1-5f5a790892ab\">Herunterladen<\/a><\/div>\n\n\n\n<p>Am 18.4.2026 fand das traditionelle Fr\u00fchjahrsturnier im Sportcenter UniCredit Kaiserwasser mit neuer Rekordbeteiligung statt. Die Ergebnistafel ist anbei.<br>Im Anschluss gab es dann die gro\u00dfe Saisonabschlussfeier mit rd. 70 Teilnehmerinnen und Teilnehmern. <br>Besonders gefreut hat uns dieses Jahr die Teilnahme von Teilnehmern und Teilnehmerinnen der Parkinson-Gruppe von POST SV im B-Bewerb.<br><br>Der Vorstand bedankt sich besonders bei Robert Mantl und G\u00fcnter Stutzenberger von POST SV f\u00fcr das Sponsoring der diesj\u00e4hrigen Abschlussveranstaltung. Neben der Siegerehrung f\u00fcr das Turnier und die abgelaufene Meisterschaft wurde bei einem k\u00f6stlichen Buffet im Kaiserwasser Restaurant noch lange und ausgiebig gefeiert. Alle Ergebnisse sind im XTTV-System l\u00fcckenlos dokumentiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 18.4.2026 fand das traditionelle Fr\u00fchjahrsturnier im Sportcenter UniCredit Kaiserwasser mit neuer Rekordbeteiligung statt. Die Ergebnistafel ist anbei.Im Anschluss gab [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3038,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turniere"],"uagb_featured_image_src":{"full":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59.jpeg",2040,1530,false],"thumbnail":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59-150x150.jpeg",150,150,true],"medium":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59-300x225.jpeg",300,225,true],"medium_large":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59-768x576.jpeg",768,576,true],"large":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59-1024x768.jpeg",1024,768,true],"1536x1536":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-18-at-13.24.59.jpeg",2040,1530,false]},"uagb_author_info":{"display_name":"Achim Hartmann","author_link":"https:\/\/tt-meisterschaft.at\/ttbv\/author\/achim\/"},"uagb_comment_info":0,"uagb_excerpt":"Am 18.4.2026 fand das traditionelle Fr\u00fchjahrsturnier im Sportcenter UniCredit Kaiserwasser mit neuer Rekordbeteiligung statt. Die Ergebnistafel ist anbei.Im Anschluss gab [&hellip;]","_links":{"self":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/3036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/comments?post=3036"}],"version-history":[{"count":6,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/3036\/revisions"}],"predecessor-version":[{"id":3046,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/3036\/revisions\/3046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/media\/3038"}],"wp:attachment":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/media?parent=3036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/categories?post=3036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/tags?post=3036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}