{"id":2998,"date":"2026-04-09T08:48:00","date_gmt":"2026-04-09T06:48:00","guid":{"rendered":"https:\/\/tt-meisterschaft.at\/ttbv\/?p=2998"},"modified":"2026-04-09T13:09:44","modified_gmt":"2026-04-09T11:09:44","slug":"rettet-den-post-sv","status":"publish","type":"post","link":"https:\/\/tt-meisterschaft.at\/ttbv\/rettet-den-post-sv\/","title":{"rendered":"Rettet den Post Sport Verein"},"content":{"rendered":"\n<p>Sport ist einer der wichtigsten S\u00e4ulen in unserer Gesellschaft. <br>Helft alle mit den Post Sport Verein zu retten und unterzeichnet bitte alle die Petition!<br><br>Wir als Tischtennis Banken und Versicherungen unterst\u00fctzen den POST SV!<\/p>\n\n\n\n<p><a href=\"http:\/\/openpetition.eu\/!rettetdenpostsv\">openpetition.eu\/!rettetdenpostsv<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"648\" src=\"https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/02\/image-1024x648.png\" alt=\"\" class=\"wp-image-3023\" srcset=\"https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/02\/image-1024x648.png 1024w, https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/02\/image-300x190.png 300w, https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/02\/image-768x486.png 768w, https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2026\/02\/image.png 1372w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sport ist einer der wichtigsten S\u00e4ulen in unserer Gesellschaft. Helft alle mit den Post Sport Verein zu retten und unterzeichnet [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"uagb_featured_image_src":{"full":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501.png",499,140,false],"thumbnail":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501-150x140.png",150,140,true],"medium":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501-300x84.png",300,84,true],"medium_large":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501.png",499,140,false],"large":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501.png",499,140,false],"1536x1536":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501.png",499,140,false],"2048x2048":["https:\/\/tt-meisterschaft.at\/ttbv\/wp-content\/uploads\/2025\/11\/PostSV-Logo-e1772092934501.png",499,140,false]},"uagb_author_info":{"display_name":"Achim Hartmann","author_link":"https:\/\/tt-meisterschaft.at\/ttbv\/author\/achim\/"},"uagb_comment_info":0,"uagb_excerpt":"Sport ist einer der wichtigsten S\u00e4ulen in unserer Gesellschaft. Helft alle mit den Post Sport Verein zu retten und unterzeichnet [&hellip;]","_links":{"self":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/2998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/comments?post=2998"}],"version-history":[{"count":4,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/2998\/revisions"}],"predecessor-version":[{"id":3027,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/posts\/2998\/revisions\/3027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/media\/2909"}],"wp:attachment":[{"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/media?parent=2998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/categories?post=2998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tt-meisterschaft.at\/ttbv\/wp-json\/wp\/v2\/tags?post=2998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}